{"id":5777,"date":"2024-07-15T16:05:46","date_gmt":"2024-07-15T14:05:46","guid":{"rendered":"https:\/\/www.pixid-vms.com\/ch\/?page_id=5777"},"modified":"2024-11-19T20:29:38","modified_gmt":"2024-11-19T18:29:38","slug":"blog-it","status":"publish","type":"page","link":"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/","title":{"rendered":"Blog PIXID VMS &#8211; Notizie &amp; Attualit\u00e0"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5777\" class=\"elementor elementor-5777\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3228906c e-con-full e-flex e-con e-parent\" data-id=\"3228906c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1c84a585 e-flex e-con-boxed e-con e-child\" data-id=\"1c84a585\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2f243e84 e-con-full e-flex e-con e-child\" data-id=\"2f243e84\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a2e3185 elementor-widget elementor-widget-heading\" data-id=\"2a2e3185\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Blog<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ad4b674 form-message elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"5ad4b674\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tScoprite gli ultimi approfondimenti e le notizie sui principali sviluppi del Gruppo PIXID e del settore del personale. Condividiamo i pi\u00f9 recenti miglioramenti tecnologici e trattiamo argomenti di attualit\u00e0 rilevanti per i nostri clienti e partner del settore. Rimanete aggiornati con le notizie pi\u00f9 importanti e gli approfondimenti esclusivi.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6dc3975f e-con-full e-flex e-con e-parent\" data-id=\"6dc3975f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-34be5d9 e-flex e-con-boxed e-con e-child\" data-id=\"34be5d9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b808c53 elementor-widget elementor-widget-global elementor-global-5298 elementor-widget-image\" data-id=\"b808c53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"480\" height=\"480\" src=\"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2024\/01\/24-01-favicon-pixid.png\" class=\"attachment-full size-full wp-image-5277\" alt=\"\" srcset=\"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2024\/01\/24-01-favicon-pixid.png 480w, https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2024\/01\/24-01-favicon-pixid-300x300.png 300w, https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2024\/01\/24-01-favicon-pixid-150x150.png 150w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d588c25 article elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"5d588c25\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;pagination_type&quot;:&quot;prev_next&quot;,&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-6699 post type-post status-publish format-standard has-post-thumbnail hentry category-blog-it\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/gestione-del-personale\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"154\" src=\"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/08\/Hybrid-workforce-strategies-300x154.jpg\" class=\"attachment-medium size-medium wp-image-6561\" alt=\"\" srcset=\"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/08\/Hybrid-workforce-strategies-300x154.jpg 300w, https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/08\/Hybrid-workforce-strategies.jpg 680w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/gestione-del-personale\/\" >\n\t\t\t\tGestione del personale: integrare permanente e temporaneo\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Gestione del personale: come integrare con successo lavoratori permanenti e temporanei In Nell&#8217;attuale panorama del lavoro, molte organizzazioni hanno gi\u00e0 adottato una qualche forma di<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/gestione-del-personale\/\" aria-label=\"Read more about Gestione del personale: integrare permanente e temporaneo\" tabindex=\"-1\" >\n\t\t\tLeggi Tutto +\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t11\/06\/2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-6154 post type-post status-publish format-standard has-post-thumbnail hentry category-blog-it\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/agenzie-lavoro-temporaneo-superare-excel\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"154\" src=\"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/03\/Excel-no-longer-enough-300x154.jpg\" class=\"attachment-medium size-medium wp-image-6083\" alt=\"\" srcset=\"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/03\/Excel-no-longer-enough-300x154.jpg 300w, https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/03\/Excel-no-longer-enough.jpg 680w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/agenzie-lavoro-temporaneo-superare-excel\/\" >\n\t\t\t\tAgenzie di lavoro temporaneo: Quando Excel non \u00e8 pi\u00f9 sufficiente\u2026\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Nonostante i suoi numerosi vantaggi, Excel mostra anche i suoi limiti man mano che le esigenze di gestione aumentano. Le agenzie alla ricerca di migliori prestazioni e sicurezza sono costrette ad adottare strumenti pi\u00f9 sofisticati&#8230;<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/agenzie-lavoro-temporaneo-superare-excel\/\" aria-label=\"Read more about Agenzie di lavoro temporaneo: Quando Excel non \u00e8 pi\u00f9 sufficiente\u2026\" tabindex=\"-1\" >\n\t\t\tLeggi Tutto +\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t26\/03\/2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-6137 post type-post status-publish format-standard has-post-thumbnail hentry category-blog-it\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/assenteismo-assunzioni-urgenti\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"154\" src=\"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/03\/Absenteeism1-300x154.jpg\" class=\"attachment-medium size-medium wp-image-6125\" alt=\"\" srcset=\"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/03\/Absenteeism1-300x154.jpg 300w, https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/03\/Absenteeism1.jpg 680w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/assenteismo-assunzioni-urgenti\/\" >\n\t\t\t\tGestire Assenteismo e Assunzioni Urgente: Soluzioni\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Scopri come affrontare l&#8217;assenteismo e le assunzioni urgenti senza bloccare la tua attivit\u00e0. Strategie e strumenti digitali per la continuit\u00e0 operativa.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/assenteismo-assunzioni-urgenti\/\" aria-label=\"Read more about Gestire Assenteismo e Assunzioni Urgente: Soluzioni\" tabindex=\"-1\" >\n\t\t\tLeggi Tutto +\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t26\/03\/2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-6114 post type-post status-publish format-standard has-post-thumbnail hentry category-blog-it\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/acquisizione-totale-talenti-tta-temporanei-permanenti\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"154\" src=\"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/03\/TTA_Bridging-the-gap-Shutterstock_347537057-300x154.jpg\" class=\"attachment-medium size-medium wp-image-6112\" alt=\"Surreal image of workers crossing a bridge between two cliffs, but the bridge is created by a magic green pencil and the pencil marking is the bridge on which they walk to the other side. It is not yet complete - so a gap is still there but being closed by the pencil. There is a Pixid VMS logo on the image,\" srcset=\"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/03\/TTA_Bridging-the-gap-Shutterstock_347537057-300x154.jpg 300w, https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/03\/TTA_Bridging-the-gap-Shutterstock_347537057.jpg 680w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/acquisizione-totale-talenti-tta-temporanei-permanenti\/\" >\n\t\t\t\tAcquisizione Totale Talenti (TTA): La Soluzione?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Combinando questi due flussi tradizionalmente separati, la TTA consente alle organizzazioni di accedere a un bacino di talenti pi\u00f9 ampio e diversificato, aumentando agilit\u00e0, efficienza e disponibilit\u00e0 della forza lavoro [&#8230;]<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/acquisizione-totale-talenti-tta-temporanei-permanenti\/\" aria-label=\"Read more about Acquisizione Totale Talenti (TTA): La Soluzione?\" tabindex=\"-1\" >\n\t\t\tLeggi Tutto +\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t19\/03\/2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-6052 post type-post status-publish format-standard has-post-thumbnail hentry category-blog-it\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/sistema-gestione-fornitori-vms\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"154\" src=\"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/02\/VMS-Advantages-1-1-300x154.jpg\" class=\"attachment-medium size-medium wp-image-6053\" alt=\"\" srcset=\"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/02\/VMS-Advantages-1-1-300x154.jpg 300w, https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/02\/VMS-Advantages-1-1.jpg 680w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/sistema-gestione-fornitori-vms\/\" >\n\t\t\t\tVendor Management System (VMS): Vantaggi e Svantaggi\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>L&#8217;uso dei sistemi di gestione delle risorse vendor (VMS) ha trasformato la gestione dei fornitori in molti settori, in particolare nel settore delle risorse umane e del personale temporaneo. Sia che siate responsabili degli acquisti, del personale o dei servizi informatici, l\u2019introduzione di un VMS pu\u00f2 offrire una centralizzazione dei processi e una migliore visibilit\u00e0 [\u2026]<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/sistema-gestione-fornitori-vms\/\" aria-label=\"Read more about Vendor Management System (VMS): Vantaggi e Svantaggi\" tabindex=\"-1\" >\n\t\t\tLeggi Tutto +\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t12\/03\/2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-6069 post type-post status-publish format-standard has-post-thumbnail hentry category-blog-it\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/pixid-ecovadis-argento\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"154\" src=\"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/02\/Ecovadis-fr-300x154.jpg\" class=\"attachment-medium size-medium wp-image-6070\" alt=\"Pixid Group logo and Ecovadis Silver Medal logo\" srcset=\"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/02\/Ecovadis-fr-300x154.jpg 300w, https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2025\/02\/Ecovadis-fr.jpg 680w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/pixid-ecovadis-argento\/\" >\n\t\t\t\tPixid Group ottiene la medaglia d&#8217;argento EcoVadis\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Gruppo Pixid ha vinto la medaglia d&#8217;argento EcoVadis, una piattaforma di analisi della RSI riconosciuta a livello mondiale. Questa distinzione ci colloca nel 94\u00b0 percentile, il che significa che siamo tra il 6% delle aziende valutate da EcoVadis pi\u00f9 classificate al mondo [&#8230;]<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/pixid-ecovadis-argento\/\" aria-label=\"Read more about Pixid Group ottiene la medaglia d&#8217;argento EcoVadis\" tabindex=\"-1\" >\n\t\t\tLeggi Tutto +\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t28\/02\/2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"3\" data-next-page=\"https:\/\/www.pixid-vms.com\/ch\/wp-json\/wp\/v2\/pages\/5777\/page\/2\/\"><\/div>\n\t\t\t\t<nav class=\"elementor-pagination\" aria-label=\"Pagination\">\n\t\t\t<span class=\"page-numbers prev\">&laquo; Previous<\/span>\n<a class=\"page-numbers next\" href=\"https:\/\/www.pixid-vms.com\/ch\/wp-json\/wp\/v2\/pages\/5777\/page\/2\/\">Next &raquo;<\/a>\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Blog Scoprite gli ultimi approfondimenti e le notizie sui principali sviluppi del Gruppo PIXID e del settore del personale. Condividiamo i pi\u00f9 recenti miglioramenti tecnologici e trattiamo argomenti di attualit\u00e0 rilevanti per i nostri clienti e partner del settore. Rimanete aggiornati con le notizie pi\u00f9 importanti e gli approfondimenti esclusivi.<\/p>\n","protected":false},"author":9,"featured_media":5774,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5777","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blog PIXID VMS - Notizie &amp; Attualit\u00e0<\/title>\n<meta name=\"description\" content=\"Trova le ultime notizie e consigli sul blog di Pixid VMS per la gestione del lavoro temporaneo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blog PIXID VMS - Notizie &amp; Attualit\u00e0\" \/>\n<meta property=\"og:description\" content=\"Trova le ultime notizie e consigli sul blog di Pixid VMS per la gestione del lavoro temporaneo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/\" \/>\n<meta property=\"og:site_name\" content=\"PIXID VMS SCHWEIZ\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-19T18:29:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2024\/06\/news-pixid-vms-1024x356.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2024\/06\/news-pixid-vms.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@PIXID_Group\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/it\\\/blog-it\\\/\",\"url\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/it\\\/blog-it\\\/\",\"name\":\"Blog PIXID VMS - Notizie &amp; Attualit\u00e0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/it\\\/blog-it\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/it\\\/blog-it\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/06\\\/thumbnail-news-pixid-vms.jpg\",\"datePublished\":\"2024-07-15T14:05:46+00:00\",\"dateModified\":\"2024-11-19T18:29:38+00:00\",\"description\":\"Trova le ultime notizie e consigli sul blog di Pixid VMS per la gestione del lavoro temporaneo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/it\\\/blog-it\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/it\\\/blog-it\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/it\\\/blog-it\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/06\\\/thumbnail-news-pixid-vms.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2024\\\/06\\\/thumbnail-news-pixid-vms.jpg\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/it\\\/blog-it\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog PIXID VMS &#8211; Notizie &amp; Attualit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/#website\",\"url\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/\",\"name\":\"PIXID VMS SCHWEIZ\",\"description\":\"External workforce management\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/#organization\",\"name\":\"PIXID VMS\",\"url\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/10\\\/PIXIDVMS-logo-colour.png\",\"contentUrl\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/10\\\/PIXIDVMS-logo-colour.png\",\"width\":3238,\"height\":625,\"caption\":\"PIXID VMS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pixid-vms.com\\\/ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/PIXID_Group\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pixid\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blog PIXID VMS - Notizie &amp; Attualit\u00e0","description":"Trova le ultime notizie e consigli sul blog di Pixid VMS per la gestione del lavoro temporaneo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/","og_locale":"de_DE","og_type":"article","og_title":"Blog PIXID VMS - Notizie &amp; Attualit\u00e0","og_description":"Trova le ultime notizie e consigli sul blog di Pixid VMS per la gestione del lavoro temporaneo.","og_url":"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/","og_site_name":"PIXID VMS SCHWEIZ","article_modified_time":"2024-11-19T18:29:38+00:00","og_image":[{"url":"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2024\/06\/news-pixid-vms-1024x356.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2024\/06\/news-pixid-vms.jpg","twitter_site":"@PIXID_Group","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/","url":"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/","name":"Blog PIXID VMS - Notizie &amp; Attualit\u00e0","isPartOf":{"@id":"https:\/\/www.pixid-vms.com\/ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/#primaryimage"},"image":{"@id":"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2024\/06\/thumbnail-news-pixid-vms.jpg","datePublished":"2024-07-15T14:05:46+00:00","dateModified":"2024-11-19T18:29:38+00:00","description":"Trova le ultime notizie e consigli sul blog di Pixid VMS per la gestione del lavoro temporaneo.","breadcrumb":{"@id":"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/#primaryimage","url":"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2024\/06\/thumbnail-news-pixid-vms.jpg","contentUrl":"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2024\/06\/thumbnail-news-pixid-vms.jpg","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/www.pixid-vms.com\/ch\/it\/blog-it\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pixid-vms.com\/ch\/"},{"@type":"ListItem","position":2,"name":"Blog PIXID VMS &#8211; Notizie &amp; Attualit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.pixid-vms.com\/ch\/#website","url":"https:\/\/www.pixid-vms.com\/ch\/","name":"PIXID VMS SCHWEIZ","description":"External workforce management","publisher":{"@id":"https:\/\/www.pixid-vms.com\/ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pixid-vms.com\/ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/www.pixid-vms.com\/ch\/#organization","name":"PIXID VMS","url":"https:\/\/www.pixid-vms.com\/ch\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/www.pixid-vms.com\/ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2022\/10\/PIXIDVMS-logo-colour.png","contentUrl":"https:\/\/www.pixid-vms.com\/ch\/wp-content\/uploads\/sites\/7\/2022\/10\/PIXIDVMS-logo-colour.png","width":3238,"height":625,"caption":"PIXID VMS"},"image":{"@id":"https:\/\/www.pixid-vms.com\/ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/PIXID_Group","https:\/\/www.linkedin.com\/company\/pixid\/"]}]}},"lang":"it","translations":{"it":5777,"fr":5776,"de":5771},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.pixid-vms.com\/ch\/wp-json\/wp\/v2\/pages\/5777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pixid-vms.com\/ch\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pixid-vms.com\/ch\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pixid-vms.com\/ch\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pixid-vms.com\/ch\/wp-json\/wp\/v2\/comments?post=5777"}],"version-history":[{"count":0,"href":"https:\/\/www.pixid-vms.com\/ch\/wp-json\/wp\/v2\/pages\/5777\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pixid-vms.com\/ch\/wp-json\/wp\/v2\/media\/5774"}],"wp:attachment":[{"href":"https:\/\/www.pixid-vms.com\/ch\/wp-json\/wp\/v2\/media?parent=5777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}